{"id":520,"date":"2019-04-08T17:57:14","date_gmt":"2019-04-08T15:57:14","guid":{"rendered":"https:\/\/manfredrischert.eu\/datenschutzerklaerung\/"},"modified":"2022-05-31T19:13:43","modified_gmt":"2022-05-31T17:13:43","slug":"datenschutzerklarung","status":"publish","type":"page","link":"https:\/\/manfredrischert.eu\/es\/datenschutzerklarung\/","title":{"rendered":"Datenschutzerkl\u00e4rung"},"content":{"rendered":"\n<!-- Legal document generated by Complianz | GDPR\/CCPA Cookie Consent https:\/\/wordpress.org\/plugins\/complianz-gdpr -->\n<div id=\"cmplz-document\" class=\"cmplz-document privacy-statement cmplz-document-eu\"><p><i>Esta declaraci\u00f3n de privacidad se actualiz\u00f3 por \u00faltima vez el 04\/04\/2024 y se aplica a los ciudadanos y residentes legales permanentes del Espacio Econ\u00f3mico Europeo y Suiza.<\/i><br \/><br \/><\/p><p><p>En esta declaraci\u00f3n de privacidad, explicamos lo que hacemos con los datos que obtenemos sobre usted a trav\u00e9s de <a href=\"https:\/\/manfredrischert.eu\/es\/\">https:\/\/manfredrischert.eu\/es\/<\/a>. Le recomendamos que lea atentamente esta declaraci\u00f3n. En nuestro tratamiento cumplimos con los requisitos de la legislaci\u00f3n sobre privacidad. Esto significa, entre otras cosas, que:<\/p><ul>\n                <li>indicamos claramente los fines para los que procesamos los datos personales. Hacemos esto por medio de esta declaraci\u00f3n de privacidad.<\/li>\n                <li>nos proponemos limitar nuestra recopilaci\u00f3n de datos personales a los datos personales necesarios para fines leg\u00edtimos;<\/li>\n                <li>en primer lugar, solicitamos su consentimiento expl\u00edcito para el tratamiento de sus datos personales en los casos en que sea necesario.<\/li>\n                <li>tomamos las medidas de seguridad adecuadas para proteger sus datos personales y tambi\u00e9n lo exigimos a las partes que procesan datos personales en nuestro nombre;<\/li>\n                <li>respetamos su derecho a acceder, rectificar o cancelar sus datos personales previa solicitud.<\/li>\n            <\/ul><p>Si tiene alguna pregunta o quiere saber exactamente qu\u00e9 datos guardamos de usted, p\u00f3ngase en contacto con nosotros.<\/p><\/p><h2>1. Prop\u00f3sito, datos y periodo de retenci\u00f3n<\/h2>Podemos recopilar o recibir informaci\u00f3n personal para un n\u00famero de prop\u00f3sitos relacionados con nuestras operaciones comerciales, que pueden incluir lo siguiente: (haga clic para expandir) <details class=\"cmplz-dropdown dropdown-privacy-statement\"><summary><div><h3>1.1 Contacto - Por tel\u00e9fono, correo, correo electr\u00f3nico y\/o formularios en el sitio<\/h3><\/div><\/summary><p class=\"cmplz-subtitle\">Para ello utilizamos los siguientes datos:<\/p><p><ul><li>Un nombre y apellido<\/li><li>Una direcci\u00f3n de casa u otra direcci\u00f3n f\u00edsica, incluyendo el nombre de la calle y el nombre de una ciudad o pueblo<\/li><li>Una direcci\u00f3n de correo electr\u00f3nico<\/li><\/ul><\/p><p class=\"cmplz-subtitle\">La base sobre la que podemos procesar estos datos es:<\/p><p><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/legal-bases\/#consent\">Tras la prestaci\u00f3n del consentimiento. <\/a><\/p><p class=\"cmplz-subtitle\">Per\u00edodo de retenci\u00f3n<\/p><p>Retendremos estos datos hasta que el servicio sea cancelado.<\/p><\/details><h2>2. Compartir con otras partes<\/h2><p>S\u00f3lo compartimos o divulgamos estos datos a los encargados del tratamiento de datos para los siguientes prop\u00f3sitos:<\/p><h2>3. Cookies<\/h2><p>Nuestra web utiliza cookies. Para m\u00e1s informaci\u00f3n acerca de las cookies, por favor consulte nuestra <a href=\"https:\/\/manfredrischert.eu\/es\/cookie-richtlinien\/\">Pol\u00edtica de cookies<\/a>.&nbsp;<\/p><h2>4. Pr\u00e1cticas de divulgaci\u00f3n<\/h2><p><p>Divulgamos informaci\u00f3n personal si nos lo exige la ley o una orden judicial, en respuesta a un organismo encargado de hacer cumplir la ley, en la medida en que lo permitan otras disposiciones legales, para proporcionar informaci\u00f3n o para una investigaci\u00f3n sobre un asunto relacionado con la seguridad p\u00fablica.<\/p><p>Si nuestro sitio web o nuestra organizaci\u00f3n son adquiridos, vendidos o participan en una fusi\u00f3n o adquisici\u00f3n, sus datos podr\u00e1n ser revelados a nuestros asesores y a los posibles compradores, y se transmitir\u00e1n a los nuevos propietarios.<\/p><\/p><p>Tenemos un Acuerdo de procesamiento de datos con Google.<\/p><p>Google no puede utilizar los datos para otros servicios de Google.<\/p><p>La inclusi\u00f3n de direcciones IP completas est\u00e1 bloqueada por nosotros.<\/p><h2>5. Seguridad<\/h2><p>Estamos comprometidos con la seguridad de los datos personales. Tomamos las medidas de seguridad adecuadas para limitar el abuso y el acceso no autorizado a los datos personales. Esto asegura que s\u00f3lo las personas necesarias tengan acceso a sus datos, que el acceso a los datos est\u00e9 protegido y que nuestras medidas de seguridad sean revisadas regularmente.<\/p><h2>6. Webs de terceros<\/h2><p>Esta declaraci\u00f3n de privacidad no se aplica a las webs de terceros conectados mediante enlaces en nuestra web. No podemos garantizar que estas terceras partes manejen sus datos personales de forma fiable o segura. Le recomendamos que lea las declaraciones de privacidad de estas webs antes de utilizarlos.<\/p><h2>7. Modificaciones de esta declaraci\u00f3n de privacidad<\/h2><p>Nos reservamos el derecho de hacer enmiendas a esta declaraci\u00f3n de privacidad. Se recomienda que consulte esta declaraci\u00f3n de privacidad regularmente para estar al tanto de cualquier cambio. Adem\u00e1s, le informaremos activamente siempre que sea posible.<\/p><h2>8. Acceso y modificaci\u00f3n de sus datos<\/h2><p>Si tiene alguna pregunta o desea saber qu\u00e9 datos personales tenemos sobre usted, p\u00f3ngase en contacto con nosotros. Puede ponerse en contacto con nosotros utilizando la siguiente informaci\u00f3n. Usted tiene los siguientes derechos:<\/p><ul>\n                <li>Usted tiene derecho a saber por qu\u00e9 se necesitan sus datos personales, qu\u00e9 pasar\u00e1 con ellos y durante cu\u00e1nto tiempo se conservar\u00e1n.<\/li>\n                <li>Derecho de acceso: Tiene derecho a acceder a los datos personales que conocemos sobre usted.<\/li>\n                <li>Derecho de rectificaci\u00f3n: tiene derecho a completar, rectificar, borrar o bloquear sus datos personales cuando lo desee.<\/li>\n                <li>Si usted nos da su consentimiento para procesar sus datos, tiene derecho a revocar dicho consentimiento y a que se eliminen sus datos personales.<\/li>\n                <li>Derecho de cesi\u00f3n de sus datos: tiene derecho a solicitar todos sus datos personales al responsable y a transferirlos \u00edntegramente a otro responsable del tratamiento de datos.<\/li>\n                <li>Derecho de oposici\u00f3n: usted puede oponerse al tratamiento de sus datos. Nosotros cumplimos con esto, a menos que existan motivos justificados para el tratamiento.<\/li>\n            <\/ul><p>Por favor, aseg\u00farese de indicar siempre claramente qui\u00e9n es usted, para que podamos estar seguros de que no modificamos o eliminamos ning\u00fan dato de la persona equivocada.<\/p><h2>9. Enviando una reclamaci\u00f3n<\/h2><p>Si no est\u00e1 satisfecho con la forma en que tratamos o procesamos sus datos personales, tiene derecho a presentar una queja a la Autoridad de protecci\u00f3n de datos.<\/p><h2>10. Datos de contacto<\/h2><p>Manfred Rischert<br \/>\n        Calle Neptuno 3<br \/>\r\n29793 Torrox<br \/>\n        Espa\u00f1a<br \/>\n        Web: <a href=\"https:\/\/manfredrischert.eu\/es\/\">https:\/\/manfredrischert.eu\/es\/<\/a> <br \/>\n        Correo electr\u00f3nico: <span class=\"cmplz-obfuscate\">i&#110;&#102;&#111;@<span class=\"cmplz-fmail-domain\">&#101;x&#046;c&#111;m<\/span>m&#097;n&#102;&#114;&#101;dris&#099;he&#114;t&#046;&#101;&#117;<\/span> <br \/>\n        N\u00famero de tel\u00e9fono: +34 608 27 51 11<\/p><h2>11. Solicitudes de Datos<\/h2><p>Para las solicitudes m\u00e1s frecuentes, tambi\u00e9n le ofrecemos la posibilidad de utilizar nuestro formulario de solicitud de datos<br \/>\t\t\t<div class=\"cmplz-datarequest cmplz-alert\">\n\t\t\t\t<span class=\"cmplz-close\">&times;<\/span>\n\t\t\t\t<span id=\"cmplz-message\"><\/span>\n\t\t\t<\/div>\n\t\t\t<form id=\"cmplz-datarequest-form\">\n\t\t\t\t<input type=\"hidden\" required value=\"eu\" name=\"cmplz_datarequest_region\" id=\"cmplz_datarequest_region\">\n\n\t\t\t\t<label for=\"cmplz_datarequest_firstname\" class=\"cmplz-first-name\">Nombre\t\t\t\t\t<input type=\"search\" class=\"datarequest-firstname\" value=\"\" placeholder=\"your first name\" id=\"cmplz_datarequest_firstname\" name=\"cmplz_datarequest_firstname\">\n\t\t\t\t<\/label>\n\t\t\t\t<div>\n\t\t\t\t\t<label for=\"cmplz_datarequest_name\">Nombre<\/label>\n\t\t\t\t\t<input type=\"text\" required value=\"\" placeholder=\"Tu nombre\" id=\"cmplz_datarequest_name\" name=\"cmplz_datarequest_name\">\n\t\t\t\t<\/div>\n\t\t\t\t<div>\n\t\t\t\t\t<label for=\"cmplz_datarequest_email\">Correo electr\u00f3nico<\/label>\n\t\t\t\t\t<input type=\"email\" required value=\"\" placeholder=\"email@email.com\" id=\"cmplz_datarequest_email\" name=\"cmplz_datarequest_email\">\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"cmplz_datarequest cmplz_datarequest_request_for_access\">\n\t\t\t\t\t\t\t<label for=\"cmplz_datarequest_request_for_access\">\n\t\t\t\t\t\t\t\t<input type=\"checkbox\" value=\"1\" name=\"cmplz_datarequest_request_for_access\" id=\"cmplz_datarequest_request_for_access\" \/>\n\t\t\t\t\t\t\t\tPresentar una solicitud de acceso a los datos que tratamos sobre usted.\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"cmplz_datarequest cmplz_datarequest_right_to_be_forgotten\">\n\t\t\t\t\t\t\t<label for=\"cmplz_datarequest_right_to_be_forgotten\">\n\t\t\t\t\t\t\t\t<input type=\"checkbox\" value=\"1\" name=\"cmplz_datarequest_right_to_be_forgotten\" id=\"cmplz_datarequest_right_to_be_forgotten\" \/>\n\t\t\t\t\t\t\t\tPresentar una solicitud de supresi\u00f3n de los datos si ya no son pertinentes.\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"cmplz_datarequest cmplz_datarequest_right_to_data_portability\">\n\t\t\t\t\t\t\t<label for=\"cmplz_datarequest_right_to_data_portability\">\n\t\t\t\t\t\t\t\t<input type=\"checkbox\" value=\"1\" name=\"cmplz_datarequest_right_to_data_portability\" id=\"cmplz_datarequest_right_to_data_portability\" \/>\n\t\t\t\t\t\t\t\tPresentar una solicitud para recibir un archivo de exportaci\u00f3n de los datos que tratamos sobre usted.\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<input type=\"button\" id=\"cmplz-datarequest-submit\" value=\"Enviar\">\n\t\t\t<\/form>\n\n\t\t\t<style>\n\t\t\t\t\/* first-name is honeypot *\/\n\t\t\t\t.cmplz-first-name {\n\t\t\t\t\tposition: absolute !important;\n\t\t\t\t\tleft: -5000px !important;\n\t\t\t\t}\n\t\t\t<\/style>\n\t\t\t<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0},"_links":{"self":[{"href":"https:\/\/manfredrischert.eu\/es\/wp-json\/wp\/v2\/pages\/520"}],"collection":[{"href":"https:\/\/manfredrischert.eu\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/manfredrischert.eu\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/manfredrischert.eu\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/manfredrischert.eu\/es\/wp-json\/wp\/v2\/comments?post=520"}],"version-history":[{"count":3,"href":"https:\/\/manfredrischert.eu\/es\/wp-json\/wp\/v2\/pages\/520\/revisions"}],"predecessor-version":[{"id":711,"href":"https:\/\/manfredrischert.eu\/es\/wp-json\/wp\/v2\/pages\/520\/revisions\/711"}],"wp:attachment":[{"href":"https:\/\/manfredrischert.eu\/es\/wp-json\/wp\/v2\/media?parent=520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}